{"id":1110,"date":"2025-02-19T00:15:54","date_gmt":"2025-02-18T23:15:54","guid":{"rendered":"https:\/\/www.lahunelle.be\/blog\/?p=1110"},"modified":"2025-07-19T05:05:22","modified_gmt":"2025-07-19T03:05:22","slug":"reception-des-porte-greffes","status":"publish","type":"post","link":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/","title":{"rendered":"R\u00e9ception des porte-greffes"},"content":{"rendered":"<p><a href=\"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19a.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-1082\" src=\"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19a-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19a-150x150.jpg 150w, https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19a-300x300.jpg 300w, https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19a-1024x1024.jpg 1024w, https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19a-768x768.jpg 768w, https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19a.jpg 1080w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>On vient de recevoir nos sujets porte-greffes !<\/p>\n<p>Ils sont la base de nos arbres fruitiers. Ils leur donnent leur vigueur, leur adaptation au sol et \u00e0 certaines maladies. D&rsquo;o\u00f9 l&rsquo;importance de connaitre le porte-greffe de l&rsquo;arbre que vous achetez !!!<\/p>\n<p><a href=\"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19aa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-1083\" src=\"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19aa-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19aa-150x150.jpg 150w, https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19aa-300x300.jpg 300w, https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19aa-1024x1024.jpg 1024w, https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19aa-768x768.jpg 768w, https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19aa.jpg 1080w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Pour le moment le sol est encore un peu trop humide pour \u00eatre travaill\u00e9. Mais d\u00e8s que possible, ces petits arbres seront plant\u00e9s en pleine terre !<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/pepinieresdelahunelle\/posts\/pfbid0AvUqE8QFBk8z9UweT2xGS1QoYBAGBnNWL3Z1MJCBrifx1ZpxK9pHZiKm3c4LMRdHl\">Publication Facebook<\/a><a href=\"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19aa.jpg\"><br \/>\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On vient de recevoir nos sujets porte-greffes ! Ils sont la base de nos arbres fruitiers. Ils leur donnent leur vigueur, leur adaptation au sol et \u00e0 certaines maladies. D&rsquo;o\u00f9 l&rsquo;importance de connaitre le porte-greffe de l&rsquo;arbre que vous achetez !!! Pour le moment le sol est encore un peu [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1082,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[2],"tags":[],"class_list":["post-1110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9ception des porte-greffes -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9ception des porte-greffes -\" \/>\n<meta property=\"og:description\" content=\"On vient de recevoir nos sujets porte-greffes ! Ils sont la base de nos arbres fruitiers. Ils leur donnent leur vigueur, leur adaptation au sol et \u00e0 certaines maladies. D&rsquo;o\u00f9 l&rsquo;importance de connaitre le porte-greffe de l&rsquo;arbre que vous achetez !!! Pour le moment le sol est encore un peu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pepinieresdelahunelle\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-18T23:15:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-19T03:05:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marie Forret\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marie Forret\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/02\\\/19\\\/reception-des-porte-greffes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/02\\\/19\\\/reception-des-porte-greffes\\\/\"},\"author\":{\"name\":\"Marie Forret\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#\\\/schema\\\/person\\\/83ca8568294425700fb26878dfaf8c6a\"},\"headline\":\"R\u00e9ception des porte-greffes\",\"datePublished\":\"2025-02-18T23:15:54+00:00\",\"dateModified\":\"2025-07-19T03:05:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/02\\\/19\\\/reception-des-porte-greffes\\\/\"},\"wordCount\":75,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/02\\\/19\\\/reception-des-porte-greffes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/2025-02-19a.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/02\\\/19\\\/reception-des-porte-greffes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/02\\\/19\\\/reception-des-porte-greffes\\\/\",\"url\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/02\\\/19\\\/reception-des-porte-greffes\\\/\",\"name\":\"R\u00e9ception des porte-greffes -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/02\\\/19\\\/reception-des-porte-greffes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/02\\\/19\\\/reception-des-porte-greffes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/2025-02-19a.jpg\",\"datePublished\":\"2025-02-18T23:15:54+00:00\",\"dateModified\":\"2025-07-19T03:05:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/02\\\/19\\\/reception-des-porte-greffes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/02\\\/19\\\/reception-des-porte-greffes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/02\\\/19\\\/reception-des-porte-greffes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9ception des porte-greffes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/\",\"name\":\"P\u00e9pini\u00e8res de la Hunelle\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#organization\",\"name\":\"P\u00e9pini\u00e8res de la Hunelle\",\"url\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-301136954_474459848024201_7287258234809584263_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-301136954_474459848024201_7287258234809584263_n.jpg\",\"width\":617,\"height\":621,\"caption\":\"P\u00e9pini\u00e8res de la Hunelle\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pepinieresdelahunelle\",\"https:\\\/\\\/www.instagram.com\\\/pepinieresdelahunelle\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#\\\/schema\\\/person\\\/83ca8568294425700fb26878dfaf8c6a\",\"name\":\"Marie Forret\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9ception des porte-greffes -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9ception des porte-greffes -","og_description":"On vient de recevoir nos sujets porte-greffes ! Ils sont la base de nos arbres fruitiers. Ils leur donnent leur vigueur, leur adaptation au sol et \u00e0 certaines maladies. D&rsquo;o\u00f9 l&rsquo;importance de connaitre le porte-greffe de l&rsquo;arbre que vous achetez !!! Pour le moment le sol est encore un peu [&hellip;]","og_url":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/","article_publisher":"https:\/\/www.facebook.com\/pepinieresdelahunelle","article_published_time":"2025-02-18T23:15:54+00:00","article_modified_time":"2025-07-19T03:05:22+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19a.jpg","type":"image\/jpeg"}],"author":"Marie Forret","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marie Forret","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/#article","isPartOf":{"@id":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/"},"author":{"name":"Marie Forret","@id":"https:\/\/www.lahunelle.be\/blog\/#\/schema\/person\/83ca8568294425700fb26878dfaf8c6a"},"headline":"R\u00e9ception des porte-greffes","datePublished":"2025-02-18T23:15:54+00:00","dateModified":"2025-07-19T03:05:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/"},"wordCount":75,"commentCount":0,"publisher":{"@id":"https:\/\/www.lahunelle.be\/blog\/#organization"},"image":{"@id":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19a.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/","url":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/","name":"R\u00e9ception des porte-greffes -","isPartOf":{"@id":"https:\/\/www.lahunelle.be\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/#primaryimage"},"image":{"@id":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/2025-02-19a.jpg","datePublished":"2025-02-18T23:15:54+00:00","dateModified":"2025-07-19T03:05:22+00:00","breadcrumb":{"@id":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lahunelle.be\/blog\/2025\/02\/19\/reception-des-porte-greffes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lahunelle.be\/blog\/"},{"@type":"ListItem","position":2,"name":"R\u00e9ception des porte-greffes"}]},{"@type":"WebSite","@id":"https:\/\/www.lahunelle.be\/blog\/#website","url":"https:\/\/www.lahunelle.be\/blog\/","name":"P\u00e9pini\u00e8res de la Hunelle","description":"","publisher":{"@id":"https:\/\/www.lahunelle.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lahunelle.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lahunelle.be\/blog\/#organization","name":"P\u00e9pini\u00e8res de la Hunelle","url":"https:\/\/www.lahunelle.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lahunelle.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/cropped-301136954_474459848024201_7287258234809584263_n.jpg","contentUrl":"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/cropped-301136954_474459848024201_7287258234809584263_n.jpg","width":617,"height":621,"caption":"P\u00e9pini\u00e8res de la Hunelle"},"image":{"@id":"https:\/\/www.lahunelle.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pepinieresdelahunelle","https:\/\/www.instagram.com\/pepinieresdelahunelle\/"]},{"@type":"Person","@id":"https:\/\/www.lahunelle.be\/blog\/#\/schema\/person\/83ca8568294425700fb26878dfaf8c6a","name":"Marie Forret"}]}},"views":24,"_links":{"self":[{"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/posts\/1110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/comments?post=1110"}],"version-history":[{"count":3,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/posts\/1110\/revisions"}],"predecessor-version":[{"id":1133,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/posts\/1110\/revisions\/1133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/media\/1082"}],"wp:attachment":[{"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/media?parent=1110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/categories?post=1110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/tags?post=1110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}