{"id":1473,"date":"2025-12-20T17:26:31","date_gmt":"2025-12-20T16:26:31","guid":{"rendered":"https:\/\/www.lahunelle.be\/blog\/?p=1473"},"modified":"2025-12-20T17:26:31","modified_gmt":"2025-12-20T16:26:31","slug":"pause-remerciement-projets-futurs","status":"publish","type":"post","link":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/","title":{"rendered":"\ud83c\udf3f Merci pour votre confiance \u2013 Une pause hivernale\u2026 et de beaux projets \u00e0 venir"},"content":{"rendered":"<p data-start=\"335\" data-end=\"524\">\u00c0 l\u2019approche des f\u00eates de fin d\u2019ann\u00e9e, les P\u00e9pini\u00e8res de la Hunelle s\u2019accordent une petite pause hivernale.<br data-start=\"442\" data-end=\"445\" \/>Un moment pour souffler, prendre du recul\u2026 et surtout pour vous dire <strong data-start=\"514\" data-end=\"523\">merci<\/strong>.<\/p>\n<p data-start=\"526\" data-end=\"855\">Merci pour votre <strong>confiance<\/strong>, pour vos <strong>visites<\/strong> \u00e0 la p\u00e9pini\u00e8re, pour vos <strong>projets<\/strong> de vergers, petits ou grands.<br data-start=\"633\" data-end=\"636\" \/>Merci pour vos questions, vos \u00e9changes, votre curiosit\u00e9, votre enthousiasme et votre envie d\u2019apprendre.<br data-start=\"719\" data-end=\"722\" \/>Chaque arbre plant\u00e9 chez vous est aussi une part de notre travail, de notre passion et de notre engagement que nous voyons grandir \ud83c\udf33<\/p>\n<h3 data-start=\"857\" data-end=\"925\">Une ann\u00e9e de rencontres, de transmission et de nature partag\u00e9e<\/h3>\n<p data-start=\"926\" data-end=\"1271\">Cette ann\u00e9e encore, nous avons eu la chance d\u2019accompagner de nombreuses familles, jardiniers amateurs, passionn\u00e9s et curieux dans leurs projets.<br data-start=\"1070\" data-end=\"1073\" \/>Planter un arbre fruitier, ce n\u2019est pas seulement acheter un arbre. C\u2019est surtout penser \u00e0 l\u2019avenir, prendre soin de sa sant\u00e9 physique et mentale, transmettre des valeurs et savourer le plaisir de moments simples en famille, en lien avec la nature.<\/p>\n<p data-start=\"1273\" data-end=\"1470\">C\u2019est exactement ce qui nous anime au quotidien aux P\u00e9pini\u00e8res de la Hunelle :\u00a0<strong data-start=\"1357\" data-end=\"1417\">transmettre le go\u00fbt et les bienfaits de l\u2019arbre fruitier<\/strong>, dans le respect du vivant et du rythme des saisons.<\/p>\n<h3 data-start=\"1472\" data-end=\"1526\">Continuer \u00e0 \u00e9voluer, pour mieux vous accompagner<\/h3>\n<p data-start=\"1527\" data-end=\"1645\">Cette pause de fin d\u2019ann\u00e9e est aussi un temps de r\u00e9flexion et de pr\u00e9paration.<br data-start=\"1604\" data-end=\"1607\" \/>Car la p\u00e9pini\u00e8re continue d\u2019\u00e9voluer \ud83c\udf31<\/p>\n<p data-start=\"1647\" data-end=\"1716\">De nouveaux projets sont en cours pour les mois et ann\u00e9es \u00e0 venir :<\/p>\n<ul data-start=\"1717\" data-end=\"2081\">\n<li data-start=\"1717\" data-end=\"1808\">\n<p data-start=\"1719\" data-end=\"1808\">enrichir encore notre offre d\u2019arbres fruitiers adapt\u00e9s \u00e0 votre terrain et \u00e0 vos envies,<\/p>\n<\/li>\n<li data-start=\"1809\" data-end=\"1890\">\n<p data-start=\"1811\" data-end=\"1890\">d\u00e9velopper davantage les <strong data-start=\"1836\" data-end=\"1887\">formations, ateliers et moments de transmission<\/strong>,<\/p>\n<\/li>\n<li data-start=\"1891\" data-end=\"1975\">\n<p data-start=\"1893\" data-end=\"1975\">am\u00e9liorer l\u2019accueil, les conseils et les outils pour vous accompagner pas \u00e0 pas,<\/p>\n<\/li>\n<li data-start=\"1976\" data-end=\"2081\">\n<p data-start=\"1978\" data-end=\"2081\">et continuer \u00e0 faire grandir la p\u00e9pini\u00e8re dans le respect de ses valeurs : <strong data-start=\"2051\" data-end=\"2080\">famille, sant\u00e9 et respect<\/strong>.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2083\" data-end=\"2253\">Nous \u00e9voluons avec l\u2019envie de faire toujours mieux, mais en gardant notre approche humaine, locale, bienveillante et passionn\u00e9e.<\/p>\n<h3 data-start=\"2255\" data-end=\"2293\">Joyeuses f\u00eates et bonne ann\u00e9e 2026<\/h3>\n<p data-start=\"2294\" data-end=\"2473\">Nous vous souhaitons de <strong data-start=\"2318\" data-end=\"2339\">tr\u00e8s belles f\u00eates et nos meilleurs v\u0153ux pour 2026. <\/strong>Que cette nouvelle ann\u00e9e soit remplie de douceur, de moments partag\u00e9s en famille, de repas gourmands\u2026 et peut-\u00eatre d\u00e9j\u00e0 de r\u00eaves de jardin pour l\u2019ann\u00e9e \u00e0 venir \u2728<\/p>\n<p data-start=\"2475\" data-end=\"2650\">Merci d\u2019\u00eatre l\u00e0, merci de faire vivre la p\u00e9pini\u00e8re \u00e0 travers vos projets.<br data-start=\"2548\" data-end=\"2551\" \/>Nous avons h\u00e2te de vous retrouver tr\u00e8s bient\u00f4t pour continuer \u00e0 faire pousser vos envies, ensemble.<\/p>\n<p data-start=\"2652\" data-end=\"2706\">\u00c0 tr\u00e8s vite,<br data-start=\"2664\" data-end=\"2667\" \/><strong data-start=\"2667\" data-end=\"2703\">Marie \u2013 P\u00e9pini\u00e8res de la Hunelle<\/strong> \ud83c\udf33<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l\u2019approche des f\u00eates de fin d\u2019ann\u00e9e, les P\u00e9pini\u00e8res de la Hunelle s\u2019accordent une petite pause hivernale.Un moment pour souffler, prendre du recul\u2026 et surtout pour vous dire merci. Merci pour votre confiance, pour vos visites \u00e0 la p\u00e9pini\u00e8re, pour vos projets de vergers, petits ou grands.Merci pour vos questions, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1474,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-1473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\ud83c\udf3f Merci pour votre confiance \u2013 Une pause hivernale\u2026 et de beaux projets \u00e0 venir -<\/title>\n<meta name=\"description\" content=\"Les P\u00e9pini\u00e8res de la Hunelle s\u2019accordent une petite pause hivernale et vous remercient pour votre confiance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf3f Merci pour votre confiance \u2013 Une pause hivernale\u2026 et de beaux projets \u00e0 venir -\" \/>\n<meta property=\"og:description\" content=\"Les P\u00e9pini\u00e8res de la Hunelle s\u2019accordent une petite pause hivernale et vous remercient pour votre confiance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pepinieresdelahunelle\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-20T16:26:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/12\/serons-fermes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marie Forret\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marie Forret\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/\"},\"author\":{\"name\":\"Marie Forret\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#\\\/schema\\\/person\\\/83ca8568294425700fb26878dfaf8c6a\"},\"headline\":\"\ud83c\udf3f Merci pour votre confiance \u2013 Une pause hivernale\u2026 et de beaux projets \u00e0 venir\",\"datePublished\":\"2025-12-20T16:26:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/\"},\"wordCount\":439,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/serons-fermes.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/\",\"url\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/\",\"name\":\"\ud83c\udf3f Merci pour votre confiance \u2013 Une pause hivernale\u2026 et de beaux projets \u00e0 venir -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/serons-fermes.jpg\",\"datePublished\":\"2025-12-20T16:26:31+00:00\",\"description\":\"Les P\u00e9pini\u00e8res de la Hunelle s\u2019accordent une petite pause hivernale et vous remercient pour votre confiance.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/serons-fermes.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/serons-fermes.jpg\",\"width\":1080,\"height\":1350,\"caption\":\"fermeture de No\u00ebl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/2025\\\/12\\\/20\\\/pause-remerciement-projets-futurs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ud83c\udf3f Merci pour votre confiance \u2013 Une pause hivernale\u2026 et de beaux projets \u00e0 venir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/\",\"name\":\"P\u00e9pini\u00e8res de la Hunelle\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#organization\",\"name\":\"P\u00e9pini\u00e8res de la Hunelle\",\"url\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-301136954_474459848024201_7287258234809584263_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-301136954_474459848024201_7287258234809584263_n.jpg\",\"width\":617,\"height\":621,\"caption\":\"P\u00e9pini\u00e8res de la Hunelle\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pepinieresdelahunelle\",\"https:\\\/\\\/www.instagram.com\\\/pepinieresdelahunelle\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lahunelle.be\\\/blog\\\/#\\\/schema\\\/person\\\/83ca8568294425700fb26878dfaf8c6a\",\"name\":\"Marie Forret\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83c\udf3f Merci pour votre confiance \u2013 Une pause hivernale\u2026 et de beaux projets \u00e0 venir -","description":"Les P\u00e9pini\u00e8res de la Hunelle s\u2019accordent une petite pause hivernale et vous remercient pour votre confiance.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/","og_locale":"fr_FR","og_type":"article","og_title":"\ud83c\udf3f Merci pour votre confiance \u2013 Une pause hivernale\u2026 et de beaux projets \u00e0 venir -","og_description":"Les P\u00e9pini\u00e8res de la Hunelle s\u2019accordent une petite pause hivernale et vous remercient pour votre confiance.","og_url":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/","article_publisher":"https:\/\/www.facebook.com\/pepinieresdelahunelle","article_published_time":"2025-12-20T16:26:31+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/12\/serons-fermes.jpg","type":"image\/jpeg"}],"author":"Marie Forret","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marie Forret","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/#article","isPartOf":{"@id":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/"},"author":{"name":"Marie Forret","@id":"https:\/\/www.lahunelle.be\/blog\/#\/schema\/person\/83ca8568294425700fb26878dfaf8c6a"},"headline":"\ud83c\udf3f Merci pour votre confiance \u2013 Une pause hivernale\u2026 et de beaux projets \u00e0 venir","datePublished":"2025-12-20T16:26:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/"},"wordCount":439,"commentCount":0,"publisher":{"@id":"https:\/\/www.lahunelle.be\/blog\/#organization"},"image":{"@id":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/12\/serons-fermes.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/","url":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/","name":"\ud83c\udf3f Merci pour votre confiance \u2013 Une pause hivernale\u2026 et de beaux projets \u00e0 venir -","isPartOf":{"@id":"https:\/\/www.lahunelle.be\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/#primaryimage"},"image":{"@id":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/12\/serons-fermes.jpg","datePublished":"2025-12-20T16:26:31+00:00","description":"Les P\u00e9pini\u00e8res de la Hunelle s\u2019accordent une petite pause hivernale et vous remercient pour votre confiance.","breadcrumb":{"@id":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/#primaryimage","url":"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/12\/serons-fermes.jpg","contentUrl":"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/12\/serons-fermes.jpg","width":1080,"height":1350,"caption":"fermeture de No\u00ebl"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lahunelle.be\/blog\/2025\/12\/20\/pause-remerciement-projets-futurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lahunelle.be\/blog\/"},{"@type":"ListItem","position":2,"name":"\ud83c\udf3f Merci pour votre confiance \u2013 Une pause hivernale\u2026 et de beaux projets \u00e0 venir"}]},{"@type":"WebSite","@id":"https:\/\/www.lahunelle.be\/blog\/#website","url":"https:\/\/www.lahunelle.be\/blog\/","name":"P\u00e9pini\u00e8res de la Hunelle","description":"","publisher":{"@id":"https:\/\/www.lahunelle.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lahunelle.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lahunelle.be\/blog\/#organization","name":"P\u00e9pini\u00e8res de la Hunelle","url":"https:\/\/www.lahunelle.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lahunelle.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/cropped-301136954_474459848024201_7287258234809584263_n.jpg","contentUrl":"https:\/\/www.lahunelle.be\/blog\/wp-content\/uploads\/2025\/07\/cropped-301136954_474459848024201_7287258234809584263_n.jpg","width":617,"height":621,"caption":"P\u00e9pini\u00e8res de la Hunelle"},"image":{"@id":"https:\/\/www.lahunelle.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pepinieresdelahunelle","https:\/\/www.instagram.com\/pepinieresdelahunelle\/"]},{"@type":"Person","@id":"https:\/\/www.lahunelle.be\/blog\/#\/schema\/person\/83ca8568294425700fb26878dfaf8c6a","name":"Marie Forret"}]}},"views":114,"_links":{"self":[{"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/posts\/1473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/comments?post=1473"}],"version-history":[{"count":1,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/posts\/1473\/revisions"}],"predecessor-version":[{"id":1475,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/posts\/1473\/revisions\/1475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/media\/1474"}],"wp:attachment":[{"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/media?parent=1473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/categories?post=1473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lahunelle.be\/blog\/wp-json\/wp\/v2\/tags?post=1473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}